{"id":4367,"count":1,"description":"","link":"https:\/\/confederaciopenyes.cat\/en\/tag\/pb-vilafranca\/","name":"PB Vilafranca","slug":"pb-vilafranca","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arxius de PB Vilafranca - Confederaci\u00f3 Mundial de Penyes del FC Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/confederaciopenyes.cat\/en\/tag\/pb-vilafranca\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arxius de PB Vilafranca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/confederaciopenyes.cat\/en\/tag\/pb-vilafranca\/\" \/>\n<meta property=\"og:site_name\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ConfePenyesFCB\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/tag\\\/pb-vilafranca\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/tag\\\/pb-vilafranca\\\/\",\"name\":\"Arxius de PB Vilafranca - Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/tag\\\/pb-vilafranca\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/tag\\\/pb-vilafranca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PB Vilafranca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"description\":\"C.M. Penyes FC Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/#organization\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"width\":512,\"height\":512,\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ConfederacioMundialPenyesFCB\",\"https:\\\/\\\/x.com\\\/ConfePenyesFCB\",\"https:\\\/\\\/www.instagram.com\\\/confepenyesfcb\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arxius de PB Vilafranca - Confederaci\u00f3 Mundial de Penyes del FC Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/confederaciopenyes.cat\/en\/tag\/pb-vilafranca\/","og_locale":"en_US","og_type":"article","og_title":"Arxius de PB Vilafranca","og_url":"https:\/\/confederaciopenyes.cat\/en\/tag\/pb-vilafranca\/","og_site_name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","twitter_card":"summary_large_image","twitter_site":"@ConfePenyesFCB","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/confederaciopenyes.cat\/en\/tag\/pb-vilafranca\/","url":"https:\/\/confederaciopenyes.cat\/en\/tag\/pb-vilafranca\/","name":"Arxius de PB Vilafranca - Confederaci\u00f3 Mundial de Penyes del FC Barcelona","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/en\/#website"},"breadcrumb":{"@id":"https:\/\/confederaciopenyes.cat\/en\/tag\/pb-vilafranca\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/confederaciopenyes.cat\/en\/tag\/pb-vilafranca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/confederaciopenyes.cat\/en\/"},{"@type":"ListItem","position":2,"name":"PB Vilafranca"}]},{"@type":"WebSite","@id":"https:\/\/confederaciopenyes.cat\/en\/#website","url":"https:\/\/confederaciopenyes.cat\/en\/","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","description":"C.M. Penyes FC Barcelona","publisher":{"@id":"https:\/\/confederaciopenyes.cat\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/confederaciopenyes.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/confederaciopenyes.cat\/en\/#organization","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","url":"https:\/\/confederaciopenyes.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/confederaciopenyes.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","width":512,"height":512,"caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","https:\/\/x.com\/ConfePenyesFCB","https:\/\/www.instagram.com\/confepenyesfcb\/"]}]}},"_links":{"self":[{"href":"https:\/\/confederaciopenyes.cat\/en\/wp-json\/wp\/v2\/tags\/4367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/confederaciopenyes.cat\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/confederaciopenyes.cat\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/confederaciopenyes.cat\/en\/wp-json\/wp\/v2\/posts?tags=4367"},{"href":"https:\/\/confederaciopenyes.cat\/en\/wp-json\/wp\/v2\/tribe_events?tags=4367"},{"href":"https:\/\/confederaciopenyes.cat\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=4367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}