{"id":25869,"date":"2024-10-01T11:39:24","date_gmt":"2024-10-01T09:39:24","guid":{"rendered":"https:\/\/confederaciopenyes.cat\/capitulo-18-la-pena-sancho\/"},"modified":"2024-10-01T12:13:20","modified_gmt":"2024-10-01T10:13:20","slug":"capitulo-18-la-pena-sancho","status":"publish","type":"post","link":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/","title":{"rendered":"Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hoy en d\u00eda, es menos corriente el hecho de bautizar a las pe\u00f1as con nombres de jugadores. De hecho, si no vamos errados, la \u00faltima pe\u00f1a fundada con el nombre de un jugador fue la <strong>Pe\u00f1a Pedrito<\/strong>, en las Islas Canarias, dedicada al jugador canario <strong>Pedro Rodr\u00edguez<\/strong>, surgido de La Mas\u00eda y de gran recuerdo entre el barcelonismo. <br\/><br\/> <\/p>\n\n<p class=\"wp-block-paragraph\">Al santoral pe\u00f1\u00edstico han subido jugadores como por ejemplo Migueli, Joan Gamper, Carles Rexach, Pep Guardiola, el Chapi Ferrer, Nadal, Marcial, Johan Cruyff, Ramon Llorens, Raich, Sadurn\u00ed, Vicen\u00e7 Piera, Marc Bartra, Gerard Piqu\u00e9, Hristo Stoichtkov, Bakero, Rivaldo, Carles Puyol, Ivan de la Pe\u00f1a, Andr\u00e9s Iniesta, Kubala, Milonguita Heredia o incluso el lejano H\u00e9ctor Scarone, que da nombre a la pe\u00f1a de Montevideo.<\/p>\n\n<p class=\"wp-block-paragraph\">Los presidentes que han dado nombres a pe\u00f1as han sido J<strong>oan Gamper, Josep Su\u00f1ol, Josep Llu\u00eds N\u00fa\u00f1ez, Joan Gaspart y Joan Laporta<\/strong>. Sin olvidarnos de <strong>Nicolau Casaus<\/strong>, del cual cinco pe\u00f1as llevan su nombre en la actualidad. Ahora bien, si hablamos de nombres curiosos, encontramos que en 1991 se fundaba en la ciudad orchatera valenciana de Alboraya una pe\u00f1a con un nombre poco corriente: <strong>Pe\u00f1a Barcelonista Juan Pablo II de Alboraya<\/strong>.  <\/p>\n\n<h6 class=\"wp-block-heading\" id=\"h-homenatge-a-agusti-sancho\"><strong>Homenaje a Agust\u00ed Sancho<\/strong><\/h6>\n\n<p class=\"wp-block-paragraph\">Pero no desviemos el tema y volvamos a los inicios de los a\u00f1os 30 cuando, siguiendo la moda, emerg\u00eda una pe\u00f1a en <strong>homenaje al gran mediocentro del Bar\u00e7a de la Edad de Oro: la Pe\u00f1a Sancho<\/strong>. Poca informaci\u00f3n tenemos, m\u00e1s all\u00e1 de que se fund\u00f3 en homenaje a Agust\u00ed Sancho, pero la importancia de este personaje merece dedicarle un cap\u00edtulo. <\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Es un jugador que quiz\u00e1s no tiene una historia de cine como la de algunos compa\u00f1eros de aquella \u00e9poca, pero, sin ning\u00fan tipo de duda, fue una <strong>pieza clave en el que ha sido el segundo mejor periodo de la historia del FC Barcelona: el Bar\u00e7a de la Edad de Oro<\/strong>. Haciendo comparaciones en el tiempo y en la personalidad, el papel de Sancho en aquel equipo <strong>podr\u00eda compararse con el que desarroll\u00f3 Sergio Busquets en Bar\u00e7a de la \u00faltima d\u00e9cada<\/strong>. <\/p>\n\n<p class=\"wp-block-paragraph\">Agust\u00ed Sancho Agustina era<strong> natural del pueblo castellonense de Bell-lloc<\/strong>, donde naci\u00f3 el 3 de diciembre de 1896. De muy joven, la familia se traslad\u00f3 a <strong>Barcelon<\/strong>a y empez\u00f3 a jugar a f\u00fatbol con 15 a\u00f1os en diferentes equipos de Sants. La temporada 1916\/17, pas\u00f3 al FC Barcelona <strong>sustituyendo al mediocentro Alfred Massana<\/strong>, y pronto fue un jugador importante. <strong>Estuvo en el eje de la l\u00ednea medular azulgrana hasta la temporada 1921\/1922<\/strong>, cuando se marcha otra vez a la UE Sants a causa de unas discusiones con la directiva con respecto a la renovaci\u00f3n de su licencia.  <\/p>\n\n<p class=\"wp-block-paragraph\">Evidentemente, en esta renovaci\u00f3n hab\u00eda un<strong> motivo econ\u00f3mico encubierto<\/strong>, puesto que entonces el llamado \u201camateurismo marr\u00f3n\u201d (una forma de cobrar bajo mano) era <strong>muy habitual dado que todav\u00eda no era oficial el profesionalismo en el f\u00fatbol<\/strong>. Una temporada despu\u00e9s, con Enric Cardona a la presidencia del club, <strong>Sancho volv\u00eda a vestirse de azulgrana y permaneci\u00f3 en el Bar\u00e7a hasta el a\u00f1o 1928<\/strong>. <\/p>\n\n<h6 class=\"wp-block-heading\" id=\"h-exits-esportius-i-economics\"><strong>\u00c9xitos deportivos y econ\u00f3micos<\/strong><\/h6>\n\n<p class=\"wp-block-paragraph\">El dinero ganado con el f\u00fatbol le permiti\u00f3 ir mejorando su condici\u00f3n profesional y social posteriormente, llegando a ser contratista de obras y logrando un buen nivel de vida. Sobre todo, si a\u00f1adimos que estaba contratado en el Ayuntamiento de Barcelona en un<strong> importante cargo de las obras municipales<\/strong>. Sus compa\u00f1eros de equipo<strong> criticaban su car\u00e1cter r\u00e1cano<\/strong>, pero gracias a esta obsesi\u00f3n ahorradora no pas\u00f3 las penurias como otros despu\u00e9s de la retirada del f\u00fatbol.  <\/p>\n\n<p class=\"wp-block-paragraph\">Agust\u00ed Sancho fue<strong> cinco veces campe\u00f3n de Espa\u00f1a y nueve de Catalu\u00f1a<\/strong>. Jug\u00f3 tres veces con la Selecci\u00f3n Espa\u00f1ola entre 1920 y 1923. Cabe destacar la primera aparici\u00f3n, <strong>en los Juegos Ol\u00edmpicos de Amberes de 1920, donde Espa\u00f1a se colg\u00f3 la medalla de plata con Sancho como integrante<\/strong>.  <\/p>\n\n<p class=\"wp-block-paragraph\">Agust\u00ed Sancho <strong>muri\u00f3 el 25 de agosto de 1960, en la edad de 63 a\u00f1os<\/strong>.<\/p>\n\n<p class=\"wp-block-paragraph\">Una de las an\u00e9cdotas que circulan como una leyenda en clave azulgrana era la habilidad de Sancho para <strong>parar la pelota con el pecho, hacerla rodar en su m\u00e1s que marcada panza y chutarla con fuerza sin que cayera en el suelo<\/strong>. Esta jugada creaba el delirio de los barcelonistas citados en el campo de la Calle Industria o, posteriormente, en el flamante y estrenado nuevo estadio de Les Corts. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy en d\u00eda, es menos corriente el hecho de bautizar a las pe\u00f1as con nombres de jugadores. De hecho, si no vamos errados, la \u00faltima pe\u00f1a fundada con el nombre de un jugador fue la Pe\u00f1a Pedrito, en las Islas Canarias, dedicada al jugador canario Pedro Rodr\u00edguez, surgido de La Mas\u00eda y de gran recuerdo &#8230; <a title=\"Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho\" class=\"read-more\" href=\"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/\" aria-label=\"Leer m\u00e1s sobre Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":4,"featured_media":25847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2802],"tags":[3154,2556,2629,2555,3153],"class_list":["post-25869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia-penyes-es","tag-agusti-sancho-es","tag-confederacio-mundial-de-penyes-es-2","tag-historia-es-2","tag-penas-es","tag-penya-sancho-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho - Confederaci\u00f3 Mundial Penyes<\/title>\n<meta name=\"description\" content=\"La Pe\u00f1a Sancho homenaje\u00f3 Agust\u00ed Sancho, una pieza clave del Bar\u00e7a de la Edad de Oro, una de las etapas m\u00e1s brillantes de la historia del Bar\u00e7a.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho\" \/>\n<meta property=\"og:description\" content=\"La Pe\u00f1a Sancho homenaje\u00f3 Agust\u00ed Sancho, una pieza clave del Bar\u00e7a de la Edad de Oro, una de las etapas m\u00e1s brillantes de la historia del Bar\u00e7a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/\" \/>\n<meta property=\"og:site_name\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T09:39:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-01T10:13:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Penya-Sancho.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ConfePenyesFCB\" \/>\n<meta name=\"twitter:site\" content=\"@ConfePenyesFCB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/\"},\"author\":{\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/person\\\/337072f6daef87a85aa59aa1f134387c\"},\"headline\":\"Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho\",\"datePublished\":\"2024-10-01T09:39:24+00:00\",\"dateModified\":\"2024-10-01T10:13:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/\"},\"wordCount\":767,\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Penya-Sancho.jpg\",\"keywords\":[\"Agust\u00ed Sancho\",\"confederaci\u00f3 mundial de penyes\",\"Historia\",\"pe\u00f1as\",\"Penya Sancho\"],\"articleSection\":[\"Historia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/\",\"name\":\"Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho - Confederaci\u00f3 Mundial Penyes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Penya-Sancho.jpg\",\"datePublished\":\"2024-10-01T09:39:24+00:00\",\"dateModified\":\"2024-10-01T10:13:20+00:00\",\"description\":\"La Pe\u00f1a Sancho homenaje\u00f3 Agust\u00ed Sancho, una pieza clave del Bar\u00e7a de la Edad de Oro, una de las etapas m\u00e1s brillantes de la historia del Bar\u00e7a.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Penya-Sancho.jpg\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Penya-Sancho.jpg\",\"width\":1200,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/capitulo-18-la-pena-sancho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"description\":\"C.M. Penyes FC Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"width\":512,\"height\":512,\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ConfederacioMundialPenyesFCB\",\"https:\\\/\\\/x.com\\\/ConfePenyesFCB\",\"https:\\\/\\\/www.instagram.com\\\/confepenyesfcb\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/person\\\/337072f6daef87a85aa59aa1f134387c\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/author\\\/comunicacioconfederaciopenyes-cat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho - Confederaci\u00f3 Mundial Penyes","description":"La Pe\u00f1a Sancho homenaje\u00f3 Agust\u00ed Sancho, una pieza clave del Bar\u00e7a de la Edad de Oro, una de las etapas m\u00e1s brillantes de la historia del Bar\u00e7a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/","og_locale":"es_ES","og_type":"article","og_title":"Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho","og_description":"La Pe\u00f1a Sancho homenaje\u00f3 Agust\u00ed Sancho, una pieza clave del Bar\u00e7a de la Edad de Oro, una de las etapas m\u00e1s brillantes de la historia del Bar\u00e7a.","og_url":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/","og_site_name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","article_publisher":"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","article_published_time":"2024-10-01T09:39:24+00:00","article_modified_time":"2024-10-01T10:13:20+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Penya-Sancho.jpg","type":"image\/jpeg"}],"author":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","twitter_card":"summary_large_image","twitter_creator":"@ConfePenyesFCB","twitter_site":"@ConfePenyesFCB","twitter_misc":{"Escrito por":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/#article","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/"},"author":{"name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/person\/337072f6daef87a85aa59aa1f134387c"},"headline":"Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho","datePublished":"2024-10-01T09:39:24+00:00","dateModified":"2024-10-01T10:13:20+00:00","mainEntityOfPage":{"@id":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/"},"wordCount":767,"publisher":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#organization"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/#primaryimage"},"thumbnailUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Penya-Sancho.jpg","keywords":["Agust\u00ed Sancho","confederaci\u00f3 mundial de penyes","Historia","pe\u00f1as","Penya Sancho"],"articleSection":["Historia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/","url":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/","name":"Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho - Confederaci\u00f3 Mundial Penyes","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/#primaryimage"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/#primaryimage"},"thumbnailUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Penya-Sancho.jpg","datePublished":"2024-10-01T09:39:24+00:00","dateModified":"2024-10-01T10:13:20+00:00","description":"La Pe\u00f1a Sancho homenaje\u00f3 Agust\u00ed Sancho, una pieza clave del Bar\u00e7a de la Edad de Oro, una de las etapas m\u00e1s brillantes de la historia del Bar\u00e7a.","breadcrumb":{"@id":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/#primaryimage","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Penya-Sancho.jpg","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Penya-Sancho.jpg","width":1200,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/confederaciopenyes.cat\/es\/capitulo-18-la-pena-sancho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/confederaciopenyes.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Cap\u00edtulo 18 \u2013 La Pe\u00f1a Sancho"}]},{"@type":"WebSite","@id":"https:\/\/confederaciopenyes.cat\/es\/#website","url":"https:\/\/confederaciopenyes.cat\/es\/","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","description":"C.M. Penyes FC Barcelona","publisher":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/confederaciopenyes.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/confederaciopenyes.cat\/es\/#organization","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","url":"https:\/\/confederaciopenyes.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","width":512,"height":512,"caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","https:\/\/x.com\/ConfePenyesFCB","https:\/\/www.instagram.com\/confepenyesfcb\/"]},{"@type":"Person","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/person\/337072f6daef87a85aa59aa1f134387c","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"url":"https:\/\/confederaciopenyes.cat\/es\/author\/comunicacioconfederaciopenyes-cat\/"}]}},"_links":{"self":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/25869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/comments?post=25869"}],"version-history":[{"count":1,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/25869\/revisions"}],"predecessor-version":[{"id":25870,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/25869\/revisions\/25870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media\/25847"}],"wp:attachment":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media?parent=25869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/categories?post=25869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/tags?post=25869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}