{"id":26537,"date":"2024-10-23T11:49:14","date_gmt":"2024-10-23T09:49:14","guid":{"rendered":"https:\/\/confederaciopenyes.cat\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/"},"modified":"2024-10-23T12:03:57","modified_gmt":"2024-10-23T10:03:57","slug":"la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso","status":"publish","type":"post","link":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/","title":{"rendered":"La bonita relaci\u00f3n entre la PB Monteagudo y el jugador Jes\u00fas Areso"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El partido entre Osasuna y Bar\u00e7a disputado a finales de septiembre en Pamplona sac\u00f3 a relucir una curiosa conexi\u00f3n entre ambos equipos. Se trata del v\u00ednculo que existe entre<strong> el jugador rojillo Jes\u00fas Areso y el presidente de la Pe\u00f1a Barcelonista de Monteagudo <\/strong>(Federaci\u00f3n de Pe\u00f1as de Arag\u00f3n, Navarra y la Rioja), <strong>Fernando Serrano<\/strong>. El jugador es natural de Cascante, una localidad muy cercana a Monteagudo, y <strong>se desplaza as\u00edduamente en el taxi conducido por Serrano<\/strong>, lo que ha ido forjando una<strong> bonita relaci\u00f3n de amistad entre ambos<\/strong>.  <\/p>\n\n<p class=\"wp-block-paragraph\">El presidente de la PB Monteagudo es tambi\u00e9n un<strong> fervoroso coleccionista azulgrana desde hace casi 40 a\u00f1os<\/strong>, y de vez en cuando organiza una <strong>exposici\u00f3n en la que muestra su porci\u00f3n personal de historia<\/strong> del FC Barcelona en forma de<strong> <\/strong>e camisetas, bufandas, botas y m\u00faltiples objetos. Coincidiendo con el partido entre Osasuna y Bar\u00e7a, Fernando Serrano mont\u00f3 la exposici\u00f3n con todos sus objetos barcelonistas, y decidi\u00f3 <strong> <\/strong>incluir <strong>una secci\u00f3n dedicada a Jes\u00fas Areso y tambi\u00e9n a su hermano Javier<\/strong>, que juega en la SD Tarazona de 1\u00aa RFEF. Como agradecimiento, <strong>ambos jugadores visitaron la muestra<\/strong> y mostraron su gratitud al presidente de la PB Monteagudo. Tambi\u00e9n firmaron algunas piezas relacionadas con ellos.  <\/p>\n\n<p class=\"wp-block-paragraph\">Esta relaci\u00f3n entre Fernando Serrano y la familia Areso demuestra <strong>la uni\u00f3n que puede generar el f\u00fatbol<\/strong>, m\u00e1s all\u00e1 del club o los colores que defiende cada uno. Esta concordia es uno de los <strong>valores que promulga desde siempre la Confederaci\u00f3 Mundial de Penyes del FC Barcelona<\/strong>, as\u00ed como <strong><a href=\"http:\/\/aficionesunidas.es\" target=\"_blank\" rel=\"noreferrer noopener\">Aficiones Unidas<\/a><\/strong>, entidad a la cual pertenece junto a otras 33 federaciones de pe\u00f1as del f\u00fatbol espa\u00f1ol. <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_24b4a478-1.jpg\"><img decoding=\"async\" width=\"900\" height=\"1200\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_24b4a478-1-edited.jpg\" alt=\"\" class=\"wp-image-26530 lazyload\" style=\"--smush-placeholder-width: 900px; --smush-placeholder-aspect-ratio: 900\/1200;width:365px;height:auto\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_24b4a478-1-edited.jpg 900w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_24b4a478-1-edited-225x300.jpg 225w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_24b4a478-1-edited-768x1024.jpg 768w\" data-sizes=\"(max-width: 900px) 100vw, 900px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>El partido entre Osasuna y Bar\u00e7a disputado a finales de septiembre en Pamplona sac\u00f3 a relucir una curiosa conexi\u00f3n entre ambos equipos. Se trata del v\u00ednculo que existe entre el jugador rojillo Jes\u00fas Areso y el presidente de la Pe\u00f1a Barcelonista de Monteagudo (Federaci\u00f3n de Pe\u00f1as de Arag\u00f3n, Navarra y la Rioja), Fernando Serrano. El &#8230; <a title=\"La bonita relaci\u00f3n entre la PB Monteagudo y el jugador Jes\u00fas Areso\" class=\"read-more\" href=\"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/\" aria-label=\"Leer m\u00e1s sobre La bonita relaci\u00f3n entre la PB Monteagudo y el jugador Jes\u00fas Areso\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":4,"featured_media":26535,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[78],"tags":[2594,3236,2595,3147,2555],"class_list":["post-26537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-en","tag-confederacio-mundial-de-penyes-es-3","tag-jesus-areso-es","tag-noticias-es-2","tag-pb-monteagudo-es","tag-penas-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La relaci\u00f3n entre la PB Monteagudo y Jes\u00fas Areso - C. M. Penyes<\/title>\n<meta name=\"description\" content=\"Jes\u00fas Areso visit\u00f3 la exposici\u00f3n azulgrana de Fernando Serrano, presidente de la PB Monteagudo, con quien mantiene una gran amistad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La bonita relaci\u00f3n entre la PB Monteagudo y el jugador Jes\u00fas Areso\" \/>\n<meta property=\"og:description\" content=\"Jes\u00fas Areso visit\u00f3 la exposici\u00f3n azulgrana de Fernando Serrano, presidente de la PB Monteagudo, con quien mantiene una gran amistad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/\" \/>\n<meta property=\"og:site_name\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-23T09:49:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-23T10:03:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_e40c7ff9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1561\" \/>\n\t<meta property=\"og:image:height\" content=\"808\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ConfePenyesFCB\" \/>\n<meta name=\"twitter:site\" content=\"@ConfePenyesFCB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/\"},\"author\":{\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/person\\\/337072f6daef87a85aa59aa1f134387c\"},\"headline\":\"La bonita relaci\u00f3n entre la PB Monteagudo y el jugador Jes\u00fas Areso\",\"datePublished\":\"2024-10-23T09:49:14+00:00\",\"dateModified\":\"2024-10-23T10:03:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/\"},\"wordCount\":306,\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_e40c7ff9.jpg\",\"keywords\":[\"confederaci\u00f3 mundial de penyes\",\"Jes\u00fas Areso\",\"noticias\",\"PB Monteagudo\",\"pe\u00f1as\"],\"articleSection\":[\"News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/\",\"name\":\"La relaci\u00f3n entre la PB Monteagudo y Jes\u00fas Areso - C. M. Penyes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_e40c7ff9.jpg\",\"datePublished\":\"2024-10-23T09:49:14+00:00\",\"dateModified\":\"2024-10-23T10:03:57+00:00\",\"description\":\"Jes\u00fas Areso visit\u00f3 la exposici\u00f3n azulgrana de Fernando Serrano, presidente de la PB Monteagudo, con quien mantiene una gran amistad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_e40c7ff9.jpg\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_e40c7ff9.jpg\",\"width\":1561,\"height\":808},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La bonita relaci\u00f3n entre la PB Monteagudo y el jugador Jes\u00fas Areso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"description\":\"C.M. Penyes FC Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"width\":512,\"height\":512,\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ConfederacioMundialPenyesFCB\",\"https:\\\/\\\/x.com\\\/ConfePenyesFCB\",\"https:\\\/\\\/www.instagram.com\\\/confepenyesfcb\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/person\\\/337072f6daef87a85aa59aa1f134387c\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/author\\\/comunicacioconfederaciopenyes-cat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La relaci\u00f3n entre la PB Monteagudo y Jes\u00fas Areso - C. M. Penyes","description":"Jes\u00fas Areso visit\u00f3 la exposici\u00f3n azulgrana de Fernando Serrano, presidente de la PB Monteagudo, con quien mantiene una gran amistad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/","og_locale":"es_ES","og_type":"article","og_title":"La bonita relaci\u00f3n entre la PB Monteagudo y el jugador Jes\u00fas Areso","og_description":"Jes\u00fas Areso visit\u00f3 la exposici\u00f3n azulgrana de Fernando Serrano, presidente de la PB Monteagudo, con quien mantiene una gran amistad.","og_url":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/","og_site_name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","article_publisher":"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","article_published_time":"2024-10-23T09:49:14+00:00","article_modified_time":"2024-10-23T10:03:57+00:00","og_image":[{"width":1561,"height":808,"url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_e40c7ff9.jpg","type":"image\/jpeg"}],"author":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","twitter_card":"summary_large_image","twitter_creator":"@ConfePenyesFCB","twitter_site":"@ConfePenyesFCB","twitter_misc":{"Escrito por":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/#article","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/"},"author":{"name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/person\/337072f6daef87a85aa59aa1f134387c"},"headline":"La bonita relaci\u00f3n entre la PB Monteagudo y el jugador Jes\u00fas Areso","datePublished":"2024-10-23T09:49:14+00:00","dateModified":"2024-10-23T10:03:57+00:00","mainEntityOfPage":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/"},"wordCount":306,"publisher":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#organization"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/#primaryimage"},"thumbnailUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_e40c7ff9.jpg","keywords":["confederaci\u00f3 mundial de penyes","Jes\u00fas Areso","noticias","PB Monteagudo","pe\u00f1as"],"articleSection":["News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/","url":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/","name":"La relaci\u00f3n entre la PB Monteagudo y Jes\u00fas Areso - C. M. Penyes","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/#primaryimage"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/#primaryimage"},"thumbnailUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_e40c7ff9.jpg","datePublished":"2024-10-23T09:49:14+00:00","dateModified":"2024-10-23T10:03:57+00:00","description":"Jes\u00fas Areso visit\u00f3 la exposici\u00f3n azulgrana de Fernando Serrano, presidente de la PB Monteagudo, con quien mantiene una gran amistad.","breadcrumb":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/#primaryimage","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_e40c7ff9.jpg","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-01-a-las-15.03.18_e40c7ff9.jpg","width":1561,"height":808},{"@type":"BreadcrumbList","@id":"https:\/\/confederaciopenyes.cat\/es\/la-bonita-relacion-entre-la-pb-monteagudo-y-el-jugador-jesus-areso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/confederaciopenyes.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La bonita relaci\u00f3n entre la PB Monteagudo y el jugador Jes\u00fas Areso"}]},{"@type":"WebSite","@id":"https:\/\/confederaciopenyes.cat\/es\/#website","url":"https:\/\/confederaciopenyes.cat\/es\/","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","description":"C.M. Penyes FC Barcelona","publisher":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/confederaciopenyes.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/confederaciopenyes.cat\/es\/#organization","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","url":"https:\/\/confederaciopenyes.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","width":512,"height":512,"caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","https:\/\/x.com\/ConfePenyesFCB","https:\/\/www.instagram.com\/confepenyesfcb\/"]},{"@type":"Person","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/person\/337072f6daef87a85aa59aa1f134387c","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"url":"https:\/\/confederaciopenyes.cat\/es\/author\/comunicacioconfederaciopenyes-cat\/"}]}},"_links":{"self":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/26537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/comments?post=26537"}],"version-history":[{"count":2,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/26537\/revisions"}],"predecessor-version":[{"id":26539,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/26537\/revisions\/26539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media\/26535"}],"wp:attachment":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media?parent=26537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/categories?post=26537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/tags?post=26537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}