{"id":29224,"date":"2025-02-13T10:32:43","date_gmt":"2025-02-13T09:32:43","guid":{"rendered":"https:\/\/confederaciopenyes.cat\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/"},"modified":"2025-02-13T10:44:46","modified_gmt":"2025-02-13T09:44:46","slug":"coloquio-con-exjugadores-del-barca-en-la-pb-minerva","status":"publish","type":"post","link":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/","title":{"rendered":"Coloquio con exjugadores del Bar\u00e7a en la PB Minerva"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El pasado fin de semana, la <strong>Pe\u00f1a Barcelonista \u201cMinerva\u201d de Nerva <\/strong>(Huelva), perteneciente a la <a href=\"https:\/\/www.fepebacm.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Federaci\u00f3n de Pe\u00f1as Barcelonistas de Andaluc\u00eda, Ceuta y Melilla<\/strong><\/a>, celebr\u00f3 un <strong>coloquio en el marco de los actos de su 25\u00ba aniversario<\/strong>. Los protagonistas fueron dos exjugadores azulgranas: <strong>Esteban Vigo Ben\u00edtez<\/strong>, conocido popularmente como \u201cBoquer\u00f3n\u201d Esteban en los a\u00f1os 80, y <strong>Patricio Rubio Bernal \u201cPatri\u201d<\/strong>, que milit\u00f3 en el Bar\u00e7a B en los a\u00f1os 90. El coloquio en la PB Minerva estuvo moderado por el periodista <strong>Alfredo Mart\u00ednez<\/strong>.  <\/p>\n\n<p class=\"wp-block-paragraph\">El presidente de la PB Minerva, <strong>Antonio L\u00f3pez<\/strong>, ejerci\u00f3 de anfitri\u00f3n del evento, en el que estuvieron presentes <strong>Jos\u00e9 Antonio Adame<\/strong>, presidente de la Federaci\u00f3n de Andaluc\u00eda, Ceuta y Melilla, y <strong>Diego Peral<\/strong>, secretario de dicha federaci\u00f3n. Tambi\u00e9n particip\u00f3 <strong>Rafael Pichardo<\/strong>, miembro de la Comisi\u00f3n Social del Club. Junto a ellos, <strong>numerosos pe\u00f1istas de la PB Minerva <\/strong>llenaron el sal\u00f3n de conferencias del Museo V\u00e1zquez D\u00edaz de la localidad de Nerva.  <\/p>\n\n<p class=\"wp-block-paragraph\">Todos los asistentes disfrutaron de una <strong>tarde llena de recuerdos y emociones barcelonistas<\/strong> a trav\u00e9s de vivencias y experiencias que contaron los tres protagonistas de la jornada. Al terminar el acto, se hizo <strong>entrega de un obsequio a 30 pe\u00f1istas que se han mantenido fieles a la PB Minerva de forma ininterrumpida durante este cuarto de siglo de historia<\/strong>. Fue un sentido homenaje a cada uno de ellos que redonde\u00f3 una jornada muy especial para todos.  <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-2.jpg\"><img decoding=\"async\" width=\"1024\" height=\"670\" data-id=\"29212\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-2-1024x670.jpg\" alt=\"\" class=\"wp-image-29212 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-2-1024x670.jpg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-2-300x196.jpg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-2-768x503.jpg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-2-1536x1005.jpg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-2.jpg 1600w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/670;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0010.jpg\"><img decoding=\"async\" width=\"1024\" height=\"473\" data-id=\"29206\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0010-1024x473.jpg\" alt=\"\" class=\"wp-image-29206 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0010-1024x473.jpg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0010-300x139.jpg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0010-768x355.jpg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0010-1536x709.jpg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0010.jpg 1600w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/473;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0007-edited.jpg\"><img decoding=\"async\" width=\"1600\" height=\"1066\" data-id=\"29216\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0007-edited.jpg\" alt=\"\" class=\"wp-image-29216 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0007-edited.jpg 1600w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0007-edited-300x200.jpg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0007-edited-1024x682.jpg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0007-edited-768x512.jpg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/IMG-20250210-WA0007-edited-1536x1023.jpg 1536w\" data-sizes=\"(max-width: 1600px) 100vw, 1600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1600px; --smush-placeholder-aspect-ratio: 1600\/1066;\" \/><\/a><\/figure>\n<\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado fin de semana, la Pe\u00f1a Barcelonista \u201cMinerva\u201d de Nerva (Huelva), perteneciente a la Federaci\u00f3n de Pe\u00f1as Barcelonistas de Andaluc\u00eda, Ceuta y Melilla, celebr\u00f3 un coloquio en el marco de los actos de su 25\u00ba aniversario. Los protagonistas fueron dos exjugadores azulgranas: Esteban Vigo Ben\u00edtez, conocido popularmente como \u201cBoquer\u00f3n\u201d Esteban en los a\u00f1os 80, &#8230; <a title=\"Coloquio con exjugadores del Bar\u00e7a en la PB Minerva\" class=\"read-more\" href=\"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/\" aria-label=\"Leer m\u00e1s sobre Coloquio con exjugadores del Bar\u00e7a en la PB Minerva\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":4,"featured_media":29198,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[3482,2594,2595,3483,2555],"class_list":["post-29224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-es","tag-colloqui","tag-confederacio-mundial-de-penyes-es-3","tag-noticias-es-2","tag-pb-minerva-es","tag-penas-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coloquio con exjugadores del Bar\u00e7a en la PB Minerva - C. M. P<\/title>\n<meta name=\"description\" content=\"Con motivo de su 25\u00ba aniversario, la PB Minerva (Huelva) hizo un coloquio con los exjugadores azulgranas &quot;Boquer\u00f3n&quot; Esteban y &quot;Patri&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coloquio con exjugadores del Bar\u00e7a en la PB Minerva\" \/>\n<meta property=\"og:description\" content=\"Con motivo de su 25\u00ba aniversario, la PB Minerva (Huelva) hizo un coloquio con los exjugadores azulgranas &quot;Boquer\u00f3n&quot; Esteban y &quot;Patri&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/\" \/>\n<meta property=\"og:site_name\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-13T09:32:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-13T09:44:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1430\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ConfePenyesFCB\" \/>\n<meta name=\"twitter:site\" content=\"@ConfePenyesFCB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/\"},\"author\":{\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/person\\\/337072f6daef87a85aa59aa1f134387c\"},\"headline\":\"Coloquio con exjugadores del Bar\u00e7a en la PB Minerva\",\"datePublished\":\"2025-02-13T09:32:43+00:00\",\"dateModified\":\"2025-02-13T09:44:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/\"},\"wordCount\":259,\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/PB-Minerva-1.jpg\",\"keywords\":[\"col\u00b7loqui\",\"confederaci\u00f3 mundial de penyes\",\"noticias\",\"PB Minerva\",\"pe\u00f1as\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/\",\"name\":\"Coloquio con exjugadores del Bar\u00e7a en la PB Minerva - C. M. P\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/PB-Minerva-1.jpg\",\"datePublished\":\"2025-02-13T09:32:43+00:00\",\"dateModified\":\"2025-02-13T09:44:46+00:00\",\"description\":\"Con motivo de su 25\u00ba aniversario, la PB Minerva (Huelva) hizo un coloquio con los exjugadores azulgranas \\\"Boquer\u00f3n\\\" Esteban y \\\"Patri\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/PB-Minerva-1.jpg\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/PB-Minerva-1.jpg\",\"width\":1430,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coloquio con exjugadores del Bar\u00e7a en la PB Minerva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"description\":\"C.M. Penyes FC Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"width\":512,\"height\":512,\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ConfederacioMundialPenyesFCB\",\"https:\\\/\\\/x.com\\\/ConfePenyesFCB\",\"https:\\\/\\\/www.instagram.com\\\/confepenyesfcb\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/person\\\/337072f6daef87a85aa59aa1f134387c\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/author\\\/comunicacioconfederaciopenyes-cat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coloquio con exjugadores del Bar\u00e7a en la PB Minerva - C. M. P","description":"Con motivo de su 25\u00ba aniversario, la PB Minerva (Huelva) hizo un coloquio con los exjugadores azulgranas \"Boquer\u00f3n\" Esteban y \"Patri\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/","og_locale":"es_ES","og_type":"article","og_title":"Coloquio con exjugadores del Bar\u00e7a en la PB Minerva","og_description":"Con motivo de su 25\u00ba aniversario, la PB Minerva (Huelva) hizo un coloquio con los exjugadores azulgranas \"Boquer\u00f3n\" Esteban y \"Patri\".","og_url":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/","og_site_name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","article_publisher":"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","article_published_time":"2025-02-13T09:32:43+00:00","article_modified_time":"2025-02-13T09:44:46+00:00","og_image":[{"width":1430,"height":721,"url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-1.jpg","type":"image\/jpeg"}],"author":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","twitter_card":"summary_large_image","twitter_creator":"@ConfePenyesFCB","twitter_site":"@ConfePenyesFCB","twitter_misc":{"Escrito por":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/#article","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/"},"author":{"name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/person\/337072f6daef87a85aa59aa1f134387c"},"headline":"Coloquio con exjugadores del Bar\u00e7a en la PB Minerva","datePublished":"2025-02-13T09:32:43+00:00","dateModified":"2025-02-13T09:44:46+00:00","mainEntityOfPage":{"@id":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/"},"wordCount":259,"publisher":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#organization"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/#primaryimage"},"thumbnailUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-1.jpg","keywords":["col\u00b7loqui","confederaci\u00f3 mundial de penyes","noticias","PB Minerva","pe\u00f1as"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/","url":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/","name":"Coloquio con exjugadores del Bar\u00e7a en la PB Minerva - C. M. P","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/#primaryimage"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/#primaryimage"},"thumbnailUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-1.jpg","datePublished":"2025-02-13T09:32:43+00:00","dateModified":"2025-02-13T09:44:46+00:00","description":"Con motivo de su 25\u00ba aniversario, la PB Minerva (Huelva) hizo un coloquio con los exjugadores azulgranas \"Boquer\u00f3n\" Esteban y \"Patri\".","breadcrumb":{"@id":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/#primaryimage","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-1.jpg","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2025\/02\/PB-Minerva-1.jpg","width":1430,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/confederaciopenyes.cat\/es\/coloquio-con-exjugadores-del-barca-en-la-pb-minerva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/confederaciopenyes.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Coloquio con exjugadores del Bar\u00e7a en la PB Minerva"}]},{"@type":"WebSite","@id":"https:\/\/confederaciopenyes.cat\/es\/#website","url":"https:\/\/confederaciopenyes.cat\/es\/","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","description":"C.M. Penyes FC Barcelona","publisher":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/confederaciopenyes.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/confederaciopenyes.cat\/es\/#organization","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","url":"https:\/\/confederaciopenyes.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","width":512,"height":512,"caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","https:\/\/x.com\/ConfePenyesFCB","https:\/\/www.instagram.com\/confepenyesfcb\/"]},{"@type":"Person","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/person\/337072f6daef87a85aa59aa1f134387c","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"url":"https:\/\/confederaciopenyes.cat\/es\/author\/comunicacioconfederaciopenyes-cat\/"}]}},"_links":{"self":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/29224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/comments?post=29224"}],"version-history":[{"count":2,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/29224\/revisions"}],"predecessor-version":[{"id":29227,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/29224\/revisions\/29227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media\/29198"}],"wp:attachment":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media?parent=29224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/categories?post=29224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/tags?post=29224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}