{"id":44609,"date":"2026-06-04T09:55:07","date_gmt":"2026-06-04T07:55:07","guid":{"rendered":"https:\/\/confederaciopenyes.cat\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/"},"modified":"2026-06-04T10:00:42","modified_gmt":"2026-06-04T08:00:42","slug":"la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea","status":"publish","type":"post","link":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/","title":{"rendered":"La PB Gante recibe la visita de Jon Andoni Goikoetxea"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El pasado fin de semana, la <strong><a href=\"https:\/\/www.facebook.com\/Pbdegante\" target=\"_blank\" rel=\"noreferrer noopener\">Penya Barcelonistas de Gante <\/a><\/strong>(Federaci\u00f3n Mundo) recibi\u00f3 a un invitado muy especial: <strong>Jon Andoni Goikoetxea<\/strong>. El exjugador azulgrana, una de las piezas clave del m\u00edtico \u201cDream Team\u201d de principios de los a\u00f1os 90, aprovech\u00f3 su viaje a la ciudad belga para<strong> visitar una de las pe\u00f1as que vive el barcelonismo con m\u00e1s pasi\u00f3n en ese pa\u00eds<\/strong>. El presidente de la PB Gante, <strong>Juan Carlos D\u00edaz<\/strong>, fue el anfitri\u00f3n perfecto para \u201cGoiko\u201d, que comparti\u00f3 un buen rato con los miembros de la pe\u00f1a y descubri\u00f3 el <strong>verdadero museo cul\u00e9 en que se ha convertido la sede de la entidad<\/strong>. De hecho, el extremo navarro estamp\u00f3 su firma en el popular coche azulgrana de Juan Carlos D\u00edaz, junto a la de otras grandes leyendas del Club.   <\/p>\n\n<p class=\"wp-block-paragraph\">La visita de Jon Andoni Goikoetxea tuvo otro protagonista de lujo: <strong>Kevin de Bruyne<\/strong>. Y es que la comitiva azulgrana <strong>visit\u00f3 la sede del torneo de f\u00fatbol Sub-15 que lleva el nombre de la estrella belga<\/strong>, la KDB Cup. De Bruyne salud\u00f3 al propio Goikoetxea y tambi\u00e9n a Juan Carlos D\u00edaz, y les agradeci\u00f3 su visita. La KDB Cup est\u00e1 considerado un<strong> torneo internacional de gran prestigio<\/strong>, por el que han pasado j\u00f3venes talentos que han llegado a la \u00e9lite del f\u00fatbol. El a\u00f1o pasado, el conjunto de La Masia del FC Barcelona disput\u00f3 el torneo y se llev\u00f3 el t\u00edtulo.    <\/p>\n\n<h6 id=\"h-passio-blaugrana-pels-quatre-costats\" class=\"wp-block-heading\"><strong>Passi\u00f3 blaugrana pels quatre costats<\/strong><\/h6>\n\n<p class=\"wp-block-paragraph\">El presidente de la Penya Barcelonistes de Gante, Juan Carlos D\u00edaz,<strong> representa todo lo que supone la pasi\u00f3n por el Bar\u00e7a, a pesar de vivir a 1.200 kil\u00f3metros de Barcelona<\/strong>. El sentimiento barcelonista de D\u00edaz se ha convertido en todo <strong>un referente dentro del mundo de las pe\u00f1as y de toda la afici\u00f3n cul\u00e9 a nivel internacional<\/strong>, y ya ha sido reconocido por diversos nombres relevantes de la historia del Club. Su s\u00edmbolo m\u00e1s popular es su <strong>coche personalizado de arriba abajo con los colores azulgranas<\/strong>, as\u00ed como todos los objetos que colecciona en su local. Por todo ello, la PB Gante se ha consolidado como la mejor embajadora del barcelonismo en Gante y tiene las puertas abiertas a todos los cul\u00e9s que viajen a la ciudad.   <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/709844457_1615308800607024_3298626701816652862_n.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"44589\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/709844457_1615308800607024_3298626701816652862_n-1024x768.jpg\" alt=\"\" class=\"wp-image-44589 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/709844457_1615308800607024_3298626701816652862_n-1024x768.jpg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/709844457_1615308800607024_3298626701816652862_n-300x225.jpg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/709844457_1615308800607024_3298626701816652862_n-768x576.jpg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/709844457_1615308800607024_3298626701816652862_n.jpg 1530w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710000637_1615329550604949_8847980095751280265_n.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"44592\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710000637_1615329550604949_8847980095751280265_n-1024x768.jpg\" alt=\"\" class=\"wp-image-44592 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710000637_1615329550604949_8847980095751280265_n-1024x768.jpg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710000637_1615329550604949_8847980095751280265_n-300x225.jpg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710000637_1615329550604949_8847980095751280265_n-768x576.jpg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710000637_1615329550604949_8847980095751280265_n-1536x1152.jpg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710000637_1615329550604949_8847980095751280265_n.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.09.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"44586\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.09-1024x576.jpeg\" alt=\"\" class=\"wp-image-44586 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.09-1024x576.jpeg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.09-300x169.jpeg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.09-768x432.jpeg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.09-1536x864.jpeg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.09.jpeg 2040w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711655011_1615308750607029_2394868171189929385_n.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"44580\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711655011_1615308750607029_2394868171189929385_n-1024x576.jpg\" alt=\"\" class=\"wp-image-44580 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711655011_1615308750607029_2394868171189929385_n-1024x576.jpg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711655011_1615308750607029_2394868171189929385_n-300x169.jpg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711655011_1615308750607029_2394868171189929385_n-768x432.jpg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711655011_1615308750607029_2394868171189929385_n-1536x864.jpg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711655011_1615308750607029_2394868171189929385_n.jpg 1600w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.11.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"44583\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.11-1024x576.jpeg\" alt=\"\" class=\"wp-image-44583 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.11-1024x576.jpeg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.11-300x169.jpeg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.11-768x432.jpeg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.11-1536x863.jpeg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-03-at-11.20.11.jpeg 1644w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711209786_1615308683940369_6927509399942694503_n.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"44597\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711209786_1615308683940369_6927509399942694503_n-1024x768.jpg\" alt=\"\" class=\"wp-image-44597 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711209786_1615308683940369_6927509399942694503_n-1024x768.jpg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711209786_1615308683940369_6927509399942694503_n-300x225.jpg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711209786_1615308683940369_6927509399942694503_n-768x576.jpg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/711209786_1615308683940369_6927509399942694503_n.jpg 1251w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El pasado fin de semana, la Penya Barcelonistas de Gante (Federaci\u00f3n Mundo) recibi\u00f3 a un invitado muy especial: Jon Andoni Goikoetxea. El exjugador azulgrana, una de las piezas clave del m\u00edtico \u201cDream Team\u201d de principios de los a\u00f1os 90, aprovech\u00f3 su viaje a la ciudad belga para visitar una de las pe\u00f1as que vive el &#8230; <a title=\"La PB Gante recibe la visita de Jon Andoni Goikoetxea\" class=\"read-more\" href=\"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/\" aria-label=\"Leer m\u00e1s sobre La PB Gante recibe la visita de Jon Andoni Goikoetxea\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":4,"featured_media":44602,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[2594,3345,4384,4385,2595,4383,2555],"class_list":["post-44609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-es","tag-confederacio-mundial-de-penyes-es-3","tag-federacion-mundo-es","tag-jon-andoni-goikoetxea","tag-kevin-de-bruyne","tag-noticias-es-2","tag-pb-gante","tag-penas-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La PB Gante recibe la visita de Jon Andoni Goikoetxea - C. M. Penyes<\/title>\n<meta name=\"description\" content=\"La PB Gante, presidida por Juan Carlos D\u00edaz, recibi\u00f3 la visita de Jon Andoni Goikoetxea en su sede para compartir recuerdos blaugranas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La PB Gante recibe la visita de Jon Andoni Goikoetxea\" \/>\n<meta property=\"og:description\" content=\"La PB Gante, presidida por Juan Carlos D\u00edaz, recibi\u00f3 la visita de Jon Andoni Goikoetxea en su sede para compartir recuerdos blaugranas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/\" \/>\n<meta property=\"og:site_name\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-04T07:55:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T08:00:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710746342_1615308833940354_2519170126143227207_n-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2040\" \/>\n\t<meta property=\"og:image:height\" content=\"1146\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ConfePenyesFCB\" \/>\n<meta name=\"twitter:site\" content=\"@ConfePenyesFCB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/\"},\"author\":{\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/person\\\/337072f6daef87a85aa59aa1f134387c\"},\"headline\":\"La PB Gante recibe la visita de Jon Andoni Goikoetxea\",\"datePublished\":\"2026-06-04T07:55:07+00:00\",\"dateModified\":\"2026-06-04T08:00:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/\"},\"wordCount\":399,\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/710746342_1615308833940354_2519170126143227207_n-1.jpg\",\"keywords\":[\"confederaci\u00f3 mundial de penyes\",\"Federaci\u00f3n Mundo\",\"Jon Andoni Goikoetxea\",\"Kevin de Bruyne\",\"noticias\",\"PB Gante\",\"pe\u00f1as\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/\",\"name\":\"La PB Gante recibe la visita de Jon Andoni Goikoetxea - C. M. Penyes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/710746342_1615308833940354_2519170126143227207_n-1.jpg\",\"datePublished\":\"2026-06-04T07:55:07+00:00\",\"dateModified\":\"2026-06-04T08:00:42+00:00\",\"description\":\"La PB Gante, presidida por Juan Carlos D\u00edaz, recibi\u00f3 la visita de Jon Andoni Goikoetxea en su sede para compartir recuerdos blaugranas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/710746342_1615308833940354_2519170126143227207_n-1.jpg\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/710746342_1615308833940354_2519170126143227207_n-1.jpg\",\"width\":2040,\"height\":1146},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La PB Gante recibe la visita de Jon Andoni Goikoetxea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"description\":\"C.M. Penyes FC Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"width\":512,\"height\":512,\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ConfederacioMundialPenyesFCB\",\"https:\\\/\\\/x.com\\\/ConfePenyesFCB\",\"https:\\\/\\\/www.instagram.com\\\/confepenyesfcb\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/person\\\/337072f6daef87a85aa59aa1f134387c\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/author\\\/comunicacioconfederaciopenyes-cat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La PB Gante recibe la visita de Jon Andoni Goikoetxea - C. M. Penyes","description":"La PB Gante, presidida por Juan Carlos D\u00edaz, recibi\u00f3 la visita de Jon Andoni Goikoetxea en su sede para compartir recuerdos blaugranas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/","og_locale":"es_ES","og_type":"article","og_title":"La PB Gante recibe la visita de Jon Andoni Goikoetxea","og_description":"La PB Gante, presidida por Juan Carlos D\u00edaz, recibi\u00f3 la visita de Jon Andoni Goikoetxea en su sede para compartir recuerdos blaugranas","og_url":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/","og_site_name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","article_publisher":"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","article_published_time":"2026-06-04T07:55:07+00:00","article_modified_time":"2026-06-04T08:00:42+00:00","og_image":[{"width":2040,"height":1146,"url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710746342_1615308833940354_2519170126143227207_n-1.jpg","type":"image\/jpeg"}],"author":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","twitter_card":"summary_large_image","twitter_creator":"@ConfePenyesFCB","twitter_site":"@ConfePenyesFCB","twitter_misc":{"Escrito por":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/#article","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/"},"author":{"name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/person\/337072f6daef87a85aa59aa1f134387c"},"headline":"La PB Gante recibe la visita de Jon Andoni Goikoetxea","datePublished":"2026-06-04T07:55:07+00:00","dateModified":"2026-06-04T08:00:42+00:00","mainEntityOfPage":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/"},"wordCount":399,"publisher":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#organization"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/#primaryimage"},"thumbnailUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710746342_1615308833940354_2519170126143227207_n-1.jpg","keywords":["confederaci\u00f3 mundial de penyes","Federaci\u00f3n Mundo","Jon Andoni Goikoetxea","Kevin de Bruyne","noticias","PB Gante","pe\u00f1as"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/","url":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/","name":"La PB Gante recibe la visita de Jon Andoni Goikoetxea - C. M. Penyes","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/#primaryimage"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/#primaryimage"},"thumbnailUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710746342_1615308833940354_2519170126143227207_n-1.jpg","datePublished":"2026-06-04T07:55:07+00:00","dateModified":"2026-06-04T08:00:42+00:00","description":"La PB Gante, presidida por Juan Carlos D\u00edaz, recibi\u00f3 la visita de Jon Andoni Goikoetxea en su sede para compartir recuerdos blaugranas","breadcrumb":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/#primaryimage","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710746342_1615308833940354_2519170126143227207_n-1.jpg","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/06\/710746342_1615308833940354_2519170126143227207_n-1.jpg","width":2040,"height":1146},{"@type":"BreadcrumbList","@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-gante-recibe-la-visita-de-jon-andoni-goikoetxea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/confederaciopenyes.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La PB Gante recibe la visita de Jon Andoni Goikoetxea"}]},{"@type":"WebSite","@id":"https:\/\/confederaciopenyes.cat\/es\/#website","url":"https:\/\/confederaciopenyes.cat\/es\/","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","description":"C.M. Penyes FC Barcelona","publisher":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/confederaciopenyes.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/confederaciopenyes.cat\/es\/#organization","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","url":"https:\/\/confederaciopenyes.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","width":512,"height":512,"caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","https:\/\/x.com\/ConfePenyesFCB","https:\/\/www.instagram.com\/confepenyesfcb\/"]},{"@type":"Person","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/person\/337072f6daef87a85aa59aa1f134387c","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"url":"https:\/\/confederaciopenyes.cat\/es\/author\/comunicacioconfederaciopenyes-cat\/"}]}},"_links":{"self":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/44609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/comments?post=44609"}],"version-history":[{"count":2,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/44609\/revisions"}],"predecessor-version":[{"id":44611,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/44609\/revisions\/44611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media\/44602"}],"wp:attachment":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media?parent=44609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/categories?post=44609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/tags?post=44609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}