{"id":46632,"date":"2026-07-14T10:35:58","date_gmt":"2026-07-14T08:35:58","guid":{"rendered":"https:\/\/confederaciopenyes.cat\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/"},"modified":"2026-07-14T10:53:06","modified_gmt":"2026-07-14T08:53:06","slug":"la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles","status":"publish","type":"post","link":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/","title":{"rendered":"La PB Camprodon celebra 45 a\u00f1os acogiendo el 21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La <strong>Penya Barcelonista Camprodon i Comarca<\/strong> vivi\u00f3 un fin de semana muy especial con motivo de la celebraci\u00f3n de su <strong>45\u00ba aniversario<\/strong>, ya que fue la anfitriona del<strong> 21\u00ba Encuentro de Pe\u00f1as Barcelonistas de Osona y Ripoll\u00e8s<\/strong>. El acontecimiento, que tuvo lugar en las localidades de <strong>Camprodon y Moll\u00f3<\/strong>, ti\u00f1\u00f3 de azulgrana el valle con la presencia de representantes de <strong>14 pe\u00f1as de la Federaci\u00f3 de Penyes d\u2019Osona i el Ripoll\u00e8s<\/strong>, que compartieron una jornada con un gran esp\u00edritu festivo. <\/p>\n\n<h6 id=\"h-conferencia-barca-i-catalunya-els-origens-de-la-simbiosi\" class=\"wp-block-heading\"><strong>Conferencia \u201cBar\u00e7a i Catalunya: Els or\u00edgens de la simbiosi\u201d<\/strong><\/h6>\n\n<p class=\"wp-block-paragraph\">La actividad comenz\u00f3 con la <strong>presentaci\u00f3n de la conferencia \u201cBar\u00e7a i Catalunya: Els or\u00edgens de la simbiosi\u201d<\/strong>, primera parte del ciclo hist\u00f3rico que ofrece la Confederaci\u00f3 Mundial de Penyes. La sesi\u00f3n tuvo lugar en el sal\u00f3n de actos del Ayuntamiento de Camprodon, y estuvo conducida por <strong>Salva Torres<\/strong>, vicepresidente de la Confederaci\u00f3, con <strong>Aksana Vayevoda<\/strong> en el apartado t\u00e9cnico. Los asistentes pudieron conocer m\u00e1s detalles sobre el <strong>estrecho v\u00ednculo entre la historia del FC Barcelona y la realidad social y pol\u00edtica catalana<\/strong>, concretamente durante los primeros a\u00f1os posteriores a la fundaci\u00f3n del Club.  <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-06-at-13.54.34-1-1.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"46625\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-06-at-13.54.34-1-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-46625 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-06-at-13.54.34-1-1-1024x768.jpeg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-06-at-13.54.34-1-1-300x225.jpeg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-06-at-13.54.34-1-1-768x576.jpeg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-06-at-13.54.34-1-1-1536x1152.jpeg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-06-at-13.54.34-1-1.jpeg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-4.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"46616\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-4-1024x768.jpeg\" alt=\"\" class=\"wp-image-46616 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-4-1024x768.jpeg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-4-300x225.jpeg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-4-768x576.jpeg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-4.jpeg 1536w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-11.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"771\" data-id=\"46622\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-11-1024x771.jpeg\" alt=\"\" class=\"wp-image-46622 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-11-1024x771.jpeg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-11-300x226.jpeg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-11-768x578.jpeg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-11-1536x1157.jpeg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.16.04-11.jpeg 2040w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/771;\" \/><\/a><\/figure>\n<\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h6 id=\"h-21a-trobada-de-penyes-d-osona-i-el-ripolles\" class=\"wp-block-heading\"><strong>21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s<\/strong><\/h6>\n\n<p class=\"wp-block-paragraph\">Al d\u00eda siguiente, los actos del 21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s se pusieron en marcha en la <strong>sede de la PB Camprodon i Comarca<\/strong>, donde se dio la bienvenida a los participantes en el evento. Destac\u00f3 la presencia de <strong>Dion\u00eds Crusellas<\/strong>, presidente de la Federaci\u00f3 de Penyes d\u2019Osona i el Ripoll\u00e8s; <strong>Antonio Escudero<\/strong>, vicepresidente del FC Barcelona; <strong>Antonio Olmo<\/strong>, exjugador y miembro de la Agrupaci\u00f3 de Jugadors del FC Barcelona; <strong>Jaume Vila<\/strong>, presidente de la PB Camprodon i Comarca; <strong>Xavier Guitart<\/strong>, alcalde de Camprodon; y <strong>Josep Coma<\/strong>, alcalde de Moll\u00f3. Todos ellos firmaron el libro de honor de la pe\u00f1a.  <\/p>\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, la comitiva azulgrana se traslad\u00f3 a Moll\u00f3, donde se celebr\u00f3 un<strong> pasacalle con los estandartes de las diversas penyes asistentes<\/strong>. Seguidamente, se llev\u00f3 a cabo una <strong>recepci\u00f3n oficial en el Ayuntamiento de Moll\u00f3<\/strong>, donde hubo intercambio de obsequios y firma del Libro de Honor. Finalmente, la comida de hermandad fue el punto culminante de este 21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s, junto con la<strong> celebraci\u00f3n del 45\u00ba aniversario de la PB Camprodon i Comarca<\/strong>. Todos los asistentes destacaron la gran trayectoria de la pe\u00f1a, que con<strong> cerca de 400 socios <\/strong>es una clara dinamizadora del barcelonismo en su territorio.   <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.56-2.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"771\" data-id=\"46600\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.56-2-1024x771.jpeg\" alt=\"\" class=\"wp-image-46600 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.56-2-1024x771.jpeg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.56-2-300x226.jpeg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.56-2-768x578.jpeg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.56-2-1536x1157.jpeg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.56-2.jpeg 2040w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/771;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-7.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"771\" data-id=\"46588\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-7-1024x771.jpeg\" alt=\"\" class=\"wp-image-46588 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-7-1024x771.jpeg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-7-300x226.jpeg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-7-768x578.jpeg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-7-1536x1157.jpeg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-7.jpeg 2040w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/771;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-5.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"771\" data-id=\"46591\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-5-1024x771.jpeg\" alt=\"\" class=\"wp-image-46591 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-5-1024x771.jpeg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-5-300x226.jpeg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-5-768x578.jpeg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-5-1536x1157.jpeg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-5.jpeg 2040w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/771;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-11.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"771\" data-id=\"46594\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-11-1024x771.jpeg\" alt=\"\" class=\"wp-image-46594 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-11-1024x771.jpeg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-11-300x226.jpeg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-11-768x578.jpeg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-11-1536x1157.jpeg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.55-11.jpeg 2040w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/771;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-1.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"771\" data-id=\"46628\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-1-1024x771.jpeg\" alt=\"\" class=\"wp-image-46628 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-1-1024x771.jpeg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-1-300x226.jpeg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-1-768x578.jpeg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-1-1536x1157.jpeg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-1.jpeg 2040w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/771;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"771\" data-id=\"46603\" data-src=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-1024x771.jpeg\" alt=\"\" class=\"wp-image-46603 lazyload\" data-srcset=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-1024x771.jpeg 1024w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-300x226.jpeg 300w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-768x578.jpeg 768w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-1536x1157.jpeg 1536w, https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54.jpeg 2040w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/771;\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Penya Barcelonista Camprodon i Comarca vivi\u00f3 un fin de semana muy especial con motivo de la celebraci\u00f3n de su 45\u00ba aniversario, ya que fue la anfitriona del 21\u00ba Encuentro de Pe\u00f1as Barcelonistas de Osona y Ripoll\u00e8s. El acontecimiento, que tuvo lugar en las localidades de Camprodon y Moll\u00f3, ti\u00f1\u00f3 de azulgrana el valle con &#8230; <a title=\"La PB Camprodon celebra 45 a\u00f1os acogiendo el 21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s\" class=\"read-more\" href=\"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/\" aria-label=\"Leer m\u00e1s sobre La PB Camprodon celebra 45 a\u00f1os acogiendo el 21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":4,"featured_media":46581,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[3353,2594,4511,2945,2595,4510,2555],"class_list":["post-46632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-es","tag-45o-aniversario","tag-confederacio-mundial-de-penyes-es-3","tag-encuentro-de-penas-osona-i-ripolles","tag-federacio-osona-i-ripolles-es","tag-noticias-es-2","tag-pb-camprodon-i-comarca","tag-penas-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s en Camprod\u00f3n- CMP<\/title>\n<meta name=\"description\" content=\"La PB Camprodon i Comarca celebr\u00f3 su 45\u00ba aniversario acogiendo la 21\u00aa Trobada de Penyes de Osona y el Ripoll\u00e8s, con la participaci\u00f3n de 14 pe\u00f1as\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La PB Camprodon celebra 45 a\u00f1os acogiendo el 21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s\" \/>\n<meta property=\"og:description\" content=\"La PB Camprodon i Comarca celebr\u00f3 su 45\u00ba aniversario acogiendo la 21\u00aa Trobada de Penyes de Osona y el Ripoll\u00e8s, con la participaci\u00f3n de 14 pe\u00f1as\" \/>\n<meta property=\"og:url\" content=\"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/\" \/>\n<meta property=\"og:site_name\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T08:35:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T08:53:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-6.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1670\" \/>\n\t<meta property=\"og:image:height\" content=\"868\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ConfePenyesFCB\" \/>\n<meta name=\"twitter:site\" content=\"@ConfePenyesFCB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/\"},\"author\":{\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/person\\\/337072f6daef87a85aa59aa1f134387c\"},\"headline\":\"La PB Camprodon celebra 45 a\u00f1os acogiendo el 21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s\",\"datePublished\":\"2026-07-14T08:35:58+00:00\",\"dateModified\":\"2026-07-14T08:53:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/\"},\"wordCount\":441,\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-11-at-19.15.54-6.jpeg\",\"keywords\":[\"45\u00ba aniversario\",\"confederaci\u00f3 mundial de penyes\",\"Encuentro de Pe\u00f1as Osona i Ripoll\u00e8s\",\"Federaci\u00f3 Osona i Ripoll\u00e8s\",\"noticias\",\"PB Camprodon i Comarca\",\"pe\u00f1as\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/\",\"name\":\"21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s en Camprod\u00f3n- CMP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-11-at-19.15.54-6.jpeg\",\"datePublished\":\"2026-07-14T08:35:58+00:00\",\"dateModified\":\"2026-07-14T08:53:06+00:00\",\"description\":\"La PB Camprodon i Comarca celebr\u00f3 su 45\u00ba aniversario acogiendo la 21\u00aa Trobada de Penyes de Osona y el Ripoll\u00e8s, con la participaci\u00f3n de 14 pe\u00f1as\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-11-at-19.15.54-6.jpeg\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-11-at-19.15.54-6.jpeg\",\"width\":1670,\"height\":868},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La PB Camprodon celebra 45 a\u00f1os acogiendo el 21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"description\":\"C.M. Penyes FC Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"width\":512,\"height\":512,\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ConfederacioMundialPenyesFCB\",\"https:\\\/\\\/x.com\\\/ConfePenyesFCB\",\"https:\\\/\\\/www.instagram.com\\\/confepenyesfcb\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/person\\\/337072f6daef87a85aa59aa1f134387c\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g\",\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/author\\\/comunicacioconfederaciopenyes-cat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s en Camprod\u00f3n- CMP","description":"La PB Camprodon i Comarca celebr\u00f3 su 45\u00ba aniversario acogiendo la 21\u00aa Trobada de Penyes de Osona y el Ripoll\u00e8s, con la participaci\u00f3n de 14 pe\u00f1as","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/","og_locale":"es_ES","og_type":"article","og_title":"La PB Camprodon celebra 45 a\u00f1os acogiendo el 21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s","og_description":"La PB Camprodon i Comarca celebr\u00f3 su 45\u00ba aniversario acogiendo la 21\u00aa Trobada de Penyes de Osona y el Ripoll\u00e8s, con la participaci\u00f3n de 14 pe\u00f1as","og_url":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/","og_site_name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","article_publisher":"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","article_published_time":"2026-07-14T08:35:58+00:00","article_modified_time":"2026-07-14T08:53:06+00:00","og_image":[{"width":1670,"height":868,"url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-6.jpeg","type":"image\/jpeg"}],"author":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","twitter_card":"summary_large_image","twitter_creator":"@ConfePenyesFCB","twitter_site":"@ConfePenyesFCB","twitter_misc":{"Escrito por":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/#article","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/"},"author":{"name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/person\/337072f6daef87a85aa59aa1f134387c"},"headline":"La PB Camprodon celebra 45 a\u00f1os acogiendo el 21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s","datePublished":"2026-07-14T08:35:58+00:00","dateModified":"2026-07-14T08:53:06+00:00","mainEntityOfPage":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/"},"wordCount":441,"publisher":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#organization"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/#primaryimage"},"thumbnailUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-6.jpeg","keywords":["45\u00ba aniversario","confederaci\u00f3 mundial de penyes","Encuentro de Pe\u00f1as Osona i Ripoll\u00e8s","Federaci\u00f3 Osona i Ripoll\u00e8s","noticias","PB Camprodon i Comarca","pe\u00f1as"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/","url":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/","name":"21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s en Camprod\u00f3n- CMP","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/#primaryimage"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/#primaryimage"},"thumbnailUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-6.jpeg","datePublished":"2026-07-14T08:35:58+00:00","dateModified":"2026-07-14T08:53:06+00:00","description":"La PB Camprodon i Comarca celebr\u00f3 su 45\u00ba aniversario acogiendo la 21\u00aa Trobada de Penyes de Osona y el Ripoll\u00e8s, con la participaci\u00f3n de 14 pe\u00f1as","breadcrumb":{"@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/#primaryimage","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-6.jpeg","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-11-at-19.15.54-6.jpeg","width":1670,"height":868},{"@type":"BreadcrumbList","@id":"https:\/\/confederaciopenyes.cat\/es\/la-pb-camprodon-celebra-45-anos-acogiendo-el-21o-encuentro-de-penas-de-osona-y-ripolles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/confederaciopenyes.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La PB Camprodon celebra 45 a\u00f1os acogiendo el 21\u00ba Encuentro de Pe\u00f1as de Osona y Ripoll\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/confederaciopenyes.cat\/es\/#website","url":"https:\/\/confederaciopenyes.cat\/es\/","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","description":"C.M. Penyes FC Barcelona","publisher":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/confederaciopenyes.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/confederaciopenyes.cat\/es\/#organization","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","url":"https:\/\/confederaciopenyes.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","width":512,"height":512,"caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","https:\/\/x.com\/ConfePenyesFCB","https:\/\/www.instagram.com\/confepenyesfcb\/"]},{"@type":"Person","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/person\/337072f6daef87a85aa59aa1f134387c","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98c60c7405ff843b10aec55db652bd3f5cb4320ef331ae76c156819a62194328?s=96&d=mm&r=g","caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"url":"https:\/\/confederaciopenyes.cat\/es\/author\/comunicacioconfederaciopenyes-cat\/"}]}},"_links":{"self":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/46632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/comments?post=46632"}],"version-history":[{"count":2,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/46632\/revisions"}],"predecessor-version":[{"id":46634,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/posts\/46632\/revisions\/46634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media\/46581"}],"wp:attachment":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media?parent=46632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/categories?post=46632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/tags?post=46632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}