{"id":25568,"date":"2024-09-17T10:38:12","date_gmt":"2024-09-17T08:38:12","guid":{"rendered":"https:\/\/confederaciopenyes.cat\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/"},"modified":"2024-09-17T10:38:12","modified_gmt":"2024-09-17T08:38:12","slug":"exposicion-fotografica-de-la-pb-dolot-i-comarca","status":"publish","type":"tribe_events","link":"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/","title":{"rendered":"Exposici\u00f3n fotogr\u00e1fica de la PB d&#8217;Olot i Comarca"},"content":{"rendered":"<p>En motivo del 50 Aniversario. Organiza AAVV Barrio Sant Ferriol.  Federaci\u00f3n del Girones, la Selva, la Garrotxa y el Pla de l&#8217;Estany.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En motivo del 50 Aniversario. Organiza AAVV Barrio Sant Ferriol. Federaci\u00f3n del Girones, la Selva, la Garrotxa y el Pla de l&#8217;Estany.<\/p>\n","protected":false},"author":5,"featured_media":25565,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-25568","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Exposici\u00f3n fotogr\u00e1fica de la PB d&#039;Olot i Comarca - Confederaci\u00f3 Mundial de Penyes del FC Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exposici\u00f3n fotogr\u00e1fica de la PB d&#039;Olot i Comarca\" \/>\n<meta property=\"og:description\" content=\"En motivo del 50 Aniversario. Organiza AAVV Barrio Sant Ferriol. Federaci\u00f3n del Girones, la Selva, la Garrotxa y el Pla de l&#8217;Estany.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/\" \/>\n<meta property=\"og:site_name\" content=\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB\" \/>\n<meta property=\"og:image\" content=\"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/09\/Imagen-de-WhatsApp-2024-09-17-a-las-10.00.41_911005fa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"962\" \/>\n\t<meta property=\"og:image:height\" content=\"1984\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ConfePenyesFCB\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/event\\\/exposicion-fotografica-de-la-pb-dolot-i-comarca\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/event\\\/exposicion-fotografica-de-la-pb-dolot-i-comarca\\\/\",\"name\":\"Exposici\u00f3n fotogr\u00e1fica de la PB d'Olot i Comarca - Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/event\\\/exposicion-fotografica-de-la-pb-dolot-i-comarca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/event\\\/exposicion-fotografica-de-la-pb-dolot-i-comarca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Imagen-de-WhatsApp-2024-09-17-a-las-10.00.41_911005fa.jpg\",\"datePublished\":\"2024-09-17T08:38:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/event\\\/exposicion-fotografica-de-la-pb-dolot-i-comarca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/event\\\/exposicion-fotografica-de-la-pb-dolot-i-comarca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/event\\\/exposicion-fotografica-de-la-pb-dolot-i-comarca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Imagen-de-WhatsApp-2024-09-17-a-las-10.00.41_911005fa.jpg\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Imagen-de-WhatsApp-2024-09-17-a-las-10.00.41_911005fa.jpg\",\"width\":962,\"height\":1984},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/event\\\/exposicion-fotografica-de-la-pb-dolot-i-comarca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Exposici\u00f3n fotogr\u00e1fica de la PB d&#8217;Olot i Comarca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"description\":\"C.M. Penyes FC Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#organization\",\"name\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"contentUrl\":\"https:\\\/\\\/confederaciopenyes.cat\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo_horizontal-1.png\",\"width\":512,\"height\":512,\"caption\":\"Confederaci\u00f3 Mundial de Penyes del FC Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/confederaciopenyes.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ConfederacioMundialPenyesFCB\",\"https:\\\/\\\/x.com\\\/ConfePenyesFCB\",\"https:\\\/\\\/www.instagram.com\\\/confepenyesfcb\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Exposici\u00f3n fotogr\u00e1fica de la PB d'Olot i Comarca - Confederaci\u00f3 Mundial de Penyes del FC Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/","og_locale":"es_ES","og_type":"article","og_title":"Exposici\u00f3n fotogr\u00e1fica de la PB d'Olot i Comarca","og_description":"En motivo del 50 Aniversario. Organiza AAVV Barrio Sant Ferriol. Federaci\u00f3n del Girones, la Selva, la Garrotxa y el Pla de l&#8217;Estany.","og_url":"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/","og_site_name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","article_publisher":"https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","og_image":[{"width":962,"height":1984,"url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/09\/Imagen-de-WhatsApp-2024-09-17-a-las-10.00.41_911005fa.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ConfePenyesFCB","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/","url":"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/","name":"Exposici\u00f3n fotogr\u00e1fica de la PB d'Olot i Comarca - Confederaci\u00f3 Mundial de Penyes del FC Barcelona","isPartOf":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/#primaryimage"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/#primaryimage"},"thumbnailUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/09\/Imagen-de-WhatsApp-2024-09-17-a-las-10.00.41_911005fa.jpg","datePublished":"2024-09-17T08:38:12+00:00","breadcrumb":{"@id":"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/#primaryimage","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/09\/Imagen-de-WhatsApp-2024-09-17-a-las-10.00.41_911005fa.jpg","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2024\/09\/Imagen-de-WhatsApp-2024-09-17-a-las-10.00.41_911005fa.jpg","width":962,"height":1984},{"@type":"BreadcrumbList","@id":"https:\/\/confederaciopenyes.cat\/es\/event\/exposicion-fotografica-de-la-pb-dolot-i-comarca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/confederaciopenyes.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/confederaciopenyes.cat\/es\/events\/"},{"@type":"ListItem","position":3,"name":"Exposici\u00f3n fotogr\u00e1fica de la PB d&#8217;Olot i Comarca"}]},{"@type":"WebSite","@id":"https:\/\/confederaciopenyes.cat\/es\/#website","url":"https:\/\/confederaciopenyes.cat\/es\/","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","description":"C.M. Penyes FC Barcelona","publisher":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/confederaciopenyes.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/confederaciopenyes.cat\/es\/#organization","name":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona","url":"https:\/\/confederaciopenyes.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","contentUrl":"https:\/\/confederaciopenyes.cat\/wp-content\/uploads\/2022\/07\/cropped-logo_horizontal-1.png","width":512,"height":512,"caption":"Confederaci\u00f3 Mundial de Penyes del FC Barcelona"},"image":{"@id":"https:\/\/confederaciopenyes.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ConfederacioMundialPenyesFCB","https:\/\/x.com\/ConfePenyesFCB","https:\/\/www.instagram.com\/confepenyesfcb\/"]}]}},"_links":{"self":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/tribe_events\/25568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/tribe_events\/25568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media\/25565"}],"wp:attachment":[{"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/media?parent=25568"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/tags?post=25568"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/confederaciopenyes.cat\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=25568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}